{"id":5979,"date":"2008-09-09T14:17:07","date_gmt":"2008-09-09T12:17:07","guid":{"rendered":"http:\/\/www.aquasoft.de\/blog\/?p=144"},"modified":"2008-09-09T14:17:07","modified_gmt":"2008-09-09T12:17:07","slug":"aquasoft-bilderwettbewerb-die-sommer-sieger-2008","status":"publish","type":"post","link":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/aquasoft-bilderwettbewerb-die-sommer-sieger-2008\/","title":{"rendered":"AquaSoft Bilderwettbewerb: Die Sommer Sieger 2008"},"content":{"rendered":"<p>Die Tage werden wieder k\u00fcrzer und k\u00fchler. Der Herbst ist im Anmarsch. Bevor er ganz bei uns eingezogen ist, pr\u00e4sentieren wir Ihnen die letzten Sieger vom Sommer 2008.<br \/>\nMit 50% aller im AquaSoft Forum abgegebenen Stimmen, wurde wieserk als Sieger f\u00fcr den Monat August ermittelt.<\/p>\n<p style=\"center\"><a href=\"https:\/\/www.aquasoft.de\/blog\/hilfe\/files\/2008\/09\/aquasoft_sieger08.jpg\" data-rel=\"lightbox-image-0\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-147 alignnone\" src=\"http:\/\/www.aquasoft.de\/blog\/wp-content\/uploads\/2008\/09\/aquasoft_sieger08-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2008\/09\/aquasoft_sieger08-300x225.jpg 300w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2008\/09\/aquasoft_sieger08.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"center\">Sieger im Bilderwettbewerb August 2008: wieserk<br \/>\nThema: \u201eWolkenbilder\u201c.<br \/>\nBild: \u201eUnd Gott erschuf die Welt&#8230;\u201d<\/p>\n<p>Im Vormonat wurden zwei Sieger ermittelt, die wir nat\u00fcrlich nicht vergessen haben.<br \/>\nDiesen Siegern und den aktuellen Gewinner, gratulieren wir an dieser Stelle.<\/p>\n<p style=\"center\"><a href=\"https:\/\/www.aquasoft.de\/blog\/hilfe\/files\/2008\/09\/aquasoft_sieger07.jpg\" data-rel=\"lightbox-image-1\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-148 alignnone\" src=\"http:\/\/www.aquasoft.de\/blog\/wp-content\/uploads\/2008\/09\/aquasoft_sieger07-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" \/><\/a><\/p>\n<p style=\"center\">Sieger im Bilderwettbewerb Juli 2008: Klaus Franz<br \/>\nThema: \u201eTierbabies\u201c<br \/>\nBild: \u201eMama, wenn ich gro\u00df bin, werde ich Dirigent!\u201c<\/p>\n<p style=\"center\"><a href=\"https:\/\/www.aquasoft.de\/blog\/hilfe\/files\/2008\/09\/aquasoft_sieger07-2.jpg\" data-rel=\"lightbox-image-2\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-149 alignnone\" src=\"http:\/\/www.aquasoft.de\/blog\/wp-content\/uploads\/2008\/09\/aquasoft_sieger07-2-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/><\/a><\/p>\n<p style=\"center\">Sieger im Bilderwettbewerb Juli 2008: htz<br \/>\nThema: \u201eTierbabies\u201c<br \/>\nBild: \u201eJungschwalben im EM-Fieber\u201c<\/p>\n<p>Die bisher eingereichten Bilder k\u00f6nnen Sie <a href=\"http:\/\/forum.aquasoft.de\/viewtopic.php?f=9&amp;t=1573\">hier<\/a> bewundern.<br \/>\nHier nehmen Sie <a href=\"http:\/\/forum.aquasoft.de\/viewtopic.php?f=9&amp;t=7403\">teil<\/a>.<br \/>\nViel Gl\u00fcck w\u00fcnscht Ihnen Ihr AquaSoft \u2013 Team!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Tage werden wieder k\u00fcrzer und k\u00fchler. Der Herbst ist im Anmarsch. Bevor er ganz bei uns eingezogen ist, pr\u00e4sentieren wir Ihnen die letzten Sieger vom Sommer 2008. Mit 50% aller im AquaSoft Forum abgegebenen Stimmen, wurde wieserk als Sieger f\u00fcr den Monat August ermittelt. Sieger im Bilderwettbewerb August 2008:&#46;&#46;&#46;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[92653],"tags":[],"class_list":["post-5979","post","type-post","status-publish","format-standard","hentry","category-nicht-kategorisiert"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"thumb-small":false,"thumb-standard":false,"thumb-medium":false,"thumb-large":false,"thumb-xlarge":false,"thumb-xxlarge":false,"yarpp-thumbnail":false},"uagb_author_info":{"display_name":"Steffen Binas","author_link":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/author\/steffenbinas\/"},"uagb_comment_info":0,"uagb_excerpt":"Die Tage werden wieder k\u00fcrzer und k\u00fchler. Der Herbst ist im Anmarsch. Bevor er ganz bei uns eingezogen ist, pr\u00e4sentieren wir Ihnen die letzten Sieger vom Sommer 2008. Mit 50% aller im AquaSoft Forum abgegebenen Stimmen, wurde wieserk als Sieger f\u00fcr den Monat August ermittelt. Sieger im Bilderwettbewerb August 2008:&#46;&#46;&#46;","_links":{"self":[{"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/posts\/5979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/comments?post=5979"}],"version-history":[{"count":0,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/posts\/5979\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/media?parent=5979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/categories?post=5979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/tags?post=5979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}