{"id":8520,"date":"2020-06-22T12:41:00","date_gmt":"2020-06-22T10:41:00","guid":{"rendered":"https:\/\/www.aquasoft.de\/blog\/hilfe\/?p=8520"},"modified":"2021-09-28T08:26:31","modified_gmt":"2021-09-28T06:26:31","slug":"textmaske-foto-durch-text-hindurch-sichtbar-machen","status":"publish","type":"post","link":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/textmaske-foto-durch-text-hindurch-sichtbar-machen\/","title":{"rendered":"Textmasken und maskierter Text &#8211; 3 Ideen zum Nachmachen"},"content":{"rendered":"\n<p>In diesem Beitrag m\u00f6chte ich zeigen, wie man mit <strong>einer Textmaske<\/strong> Teile des Bildes verdeckt oder sichtbar macht. So verbindet man ein Foto (oder Video) stilvoll mit der passenden Beschriftung.  In der Galerie gibt es drei Beispiele f\u00fcr eine Textmaske auf einem Foto zu sehen. Sie wirken etwas unterschiedlich, sind aber mit <strong>denselben Werkzeugen<\/strong> gemacht und deshalb auch alle nach dem gleichen Prinzip nachzubasteln. <br>Alles, was ich hier zeige, kann man in AquaSoft DiaShow Ultimate nachbauen, in <a href=\"https:\/\/www.aquasoft.de\/stages\">AquaSoft Stages<\/a> sind manche Feinheiten noch besser umsetzbar (aber dazu sp\u00e4ter mehr).<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/Text-Masken-Kreative-Ideen_0002_Ebene-1-1024x576.jpg\" alt=\"Text auf einem Balken als Textmaske\" data-id=\"8523\" data-link=\"https:\/\/www.aquasoft.de\/blog\/hilfe\/textmasken-und-maskierter-text-3-ideen-zum-nachmachen\/text-masken-kreative-ideen_0002_ebene-1\/\" class=\"wp-image-8523\" srcset=\"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/Text-Masken-Kreative-Ideen_0002_Ebene-1-1024x576.jpg 1024w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/Text-Masken-Kreative-Ideen_0002_Ebene-1-300x169.jpg 300w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/Text-Masken-Kreative-Ideen_0002_Ebene-1-768x432.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"blocks-gallery-item__caption\">Textmaske auf einem Balken kombiniert mit normalem Text<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/Text-Masken-Kreative-Ideen_0001_Ebene-2-1024x576.jpg\" alt=\"Textmaske auf einer wei\u00dfen Fl\u00e4che gibt den Blick auf das dahinterliegende Bild frei\" data-id=\"8522\" data-link=\"https:\/\/www.aquasoft.de\/blog\/hilfe\/textmasken-und-maskierter-text-3-ideen-zum-nachmachen\/text-masken-kreative-ideen_0001_ebene-2\/\" class=\"wp-image-8522\" srcset=\"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/Text-Masken-Kreative-Ideen_0001_Ebene-2-1024x576.jpg 1024w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/Text-Masken-Kreative-Ideen_0001_Ebene-2-300x169.jpg 300w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/Text-Masken-Kreative-Ideen_0001_Ebene-2-768x432.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"blocks-gallery-item__caption\">Hinter einer Fl\u00e4che liegt ein Bild. Durch die Buchstaben  hindurch kann man es sehen.<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/Text-Masken-Kreative-Ideen_0000_Ebene-3-1024x576.jpg\" alt=\"Text, der unter einer wei\u00dfen Linie erscheint\" data-id=\"8521\" data-link=\"https:\/\/www.aquasoft.de\/blog\/hilfe\/textmasken-und-maskierter-text-3-ideen-zum-nachmachen\/text-masken-kreative-ideen_0000_ebene-3\/\" class=\"wp-image-8521\" srcset=\"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/Text-Masken-Kreative-Ideen_0000_Ebene-3-1024x576.jpg 1024w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/Text-Masken-Kreative-Ideen_0000_Ebene-3-300x169.jpg 300w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/Text-Masken-Kreative-Ideen_0000_Ebene-3-768x432.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"blocks-gallery-item__caption\">Text kommt unter der Linie hervor und verschwindet dann wieder darunter<\/figcaption><\/figure><\/li><\/ul><\/figure>\n\n\n\t\t\t\t<div class=\"wp-block-uagb-table-of-contents uagb-toc__align-left uagb-toc__columns-1  uagb-block-4ea8ebba      \"\n\t\t\t\t\tdata-scroll= \"1\"\n\t\t\t\t\tdata-offset= \"30\"\n\t\t\t\t\tstyle=\"\"\n\t\t\t\t>\n\t\t\t\t<div class=\"uagb-toc__wrap\">\n\t\t\t\t\t\t<div class=\"uagb-toc__title\">\n\t\t\t\t\t\t\tInhalt\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uagb-toc__list-wrap \">\n\t\t\t\t\t\t<ol class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#textmaske-auf-einem-balken\" class=\"uagb-toc-link__trigger\">Textmaske auf einem Balken<\/a><ul class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#aufbau-in-der-timeline\" class=\"uagb-toc-link__trigger\">Aufbau in der Timeline<\/a><li class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#bild-und-beschriftung-einf\u00fcgen\" class=\"uagb-toc-link__trigger\">Bild und Beschriftung einf\u00fcgen<\/a><li class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#balken-bekommt-bewegung\" class=\"uagb-toc-link__trigger\">Balken bekommt Bewegung<\/a><li class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#objekte-in-dynamische-maske-einf\u00fcgen\" class=\"uagb-toc-link__trigger\">Objekte in Dynamische Maske einf\u00fcgen<\/a><\/li><\/ul><\/li><li class=\"uagb-toc__list\"><a href=\"#text-ist-ausgeschnitten-und-gibt-blick-auf-bild-frei\" class=\"uagb-toc-link__trigger\">Text ist ausgeschnitten und gibt Blick auf Bild frei<\/a><ul class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#aufbau-in-der-timeline\" class=\"uagb-toc-link__trigger\">Aufbau in der Timeline<\/a><li class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#bilder-einf\u00fcgen-mit-kameraschwenk-und-einblendung\" class=\"uagb-toc-link__trigger\">Bilder einf\u00fcgen mit Kameraschwenk und Einblendung<\/a><li class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#text-einf\u00fcgen\" class=\"uagb-toc-link__trigger\">Text einf\u00fcgen<\/a><li class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#rechteck-einsetzen-und-maske-einf\u00fcgen\" class=\"uagb-toc-link__trigger\">Rechteck einsetzen und Maske einf\u00fcgen<\/a><\/li><\/ul><\/li><\/ul><\/li><li class=\"uagb-toc__list\"><a href=\"#text-erscheint-unter-einer-linie\" class=\"uagb-toc-link__trigger\">Text erscheint unter einer Linie<\/a><ul class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#aufbau-in-der-timeline\" class=\"uagb-toc-link__trigger\">Aufbau in der Timeline<\/a><li class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#wei\u00dfe-linie-animieren\" class=\"uagb-toc-link__trigger\">Wei\u00dfe Linie animieren<\/a><li class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#text-kommt-unter-linie-hervor\" class=\"uagb-toc-link__trigger\">Text kommt unter Linie hervor<\/a><li class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#maske-einf\u00fcgen\" class=\"uagb-toc-link__trigger\">Maske einf\u00fcgen<\/a><\/ul><\/ul><\/ul><\/ol>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\n\n\n<h2 class=\"wp-block-heading\">Textmaske auf einem Balken<\/h2>\n\n\n\n<p>Hier gibt es zwei Textbereiche. Einmal sehen wir einen ganz normalen Text. Unter dem Text taucht ein <strong>Balken mit einer Textmaske<\/strong> auf. Die Textmaske wird sichtbar, w\u00e4hrend der Balken sich verl\u00e4ngert. Wir k\u00f6nnen durch die &#8222;ausgeschnittenen&#8220; Buchstaben hindurch noch Teile des Foto erkennen. Das Design eignet sich gut, wenn man den Fokus auf die zweite Zeile legen m\u00f6chte.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/Text-Masken-Kreative-Ideen_0002_Ebene-1-1024x576.jpg\" alt=\"Text auf einem Balken als Textmaske\" class=\"wp-image-8523\" width=\"768\" height=\"432\" srcset=\"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/Text-Masken-Kreative-Ideen_0002_Ebene-1-1024x576.jpg 1024w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/Text-Masken-Kreative-Ideen_0002_Ebene-1-300x169.jpg 300w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/Text-Masken-Kreative-Ideen_0002_Ebene-1-768x432.jpg 768w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption>Textmaske auf einem Balken kombiniert mit normalem Text<\/figcaption><\/figure><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Aufbau in der Timeline<\/h4>\n\n\n\n<p>In dem Kapitel, das hier in der Timeline zu sehen ist (Screenshot unten), stecken:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Ein Foto<\/li><li>Ein gew\u00f6hnlicher Text (&#8222;Ein Ausflug zum&#8230;&#8220;)<\/li><li>eine Dynamische Maske<\/li><li>Im Inhaltsbereich der Dynamischen Maske befindet sich ein Rechteck (Balken) mit einem Bewegungspfad.<\/li><li>Im Masken-Bereich befindet sich der Text.<\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/balken-mit-textmaske-und-normalem-text.jpg\" alt=\"Aufbau der Textmaske in der Timeline\" class=\"wp-image-8561\" width=\"472\" height=\"374\" srcset=\"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/balken-mit-textmaske-und-normalem-text.jpg 943w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/balken-mit-textmaske-und-normalem-text-300x238.jpg 300w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/balken-mit-textmaske-und-normalem-text-768x608.jpg 768w\" sizes=\"auto, (max-width: 472px) 100vw, 472px\" \/><\/figure><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Bild und Beschriftung einf\u00fcgen<\/h4>\n\n\n\n<p>Zuerst f\u00fcgen wir ein Kapitel ein, in das ein Foto kommt. Beim Foto sollte darauf geachtet werden, dass hier keine Einblendung kommt und dass das Foto <strong>passend zum Seitenverh\u00e4ltnis<\/strong> eingef\u00fcgt wird. In meinem Beispiel habe ich dem Foto auch noch einen ganz dezenten Kameraschwenk verpasst.<br>Darunter f\u00fcgen wir jetzt zwei Text-Objekte ein. Eines ist f\u00fcr den &#8222;gew\u00f6hnlichen&#8220; Text und das andere f\u00fcr den Text, der sp\u00e4ter als Textmaske verwendet wird. Bei diesem Text habe ich <strong>Gro\u00dfbuchstaben verwendet, die zus\u00e4tzlich auch fett <\/strong>sind. So l\u00e4sst sich sp\u00e4ter nicht nur der Text besser lesen, man erkennt auch mehr von dem Foto, das hinter dem Balken liegt. &#x1f60a;<\/p>\n\n\n\n<p>Bevor jetzt die Maske ins Spiel kommt, m\u00fcssen wir aber noch den Balken einstellen. Dazu kann man sehr gut ein Rechteck aus der Toolbox benutzen, das unter &#8222;Dynamische Formen&#8220; zu finden ist. Das Rechteck wird so <strong>zusammengezogen<\/strong> und platziert, dass es jetzt schon \u00fcber dem Schriftzug liegt, den wir als Textmaske nutzen m\u00f6chten.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Balken bekommt Bewegung<\/h4>\n\n\n\n<p>Jetzt bekommt der Balken noch eine neue Bewegungsmarke. Die neue Marke wird exakt \u00fcber der ersten platziert, aber in der Breite so stark wie m\u00f6glich verringert. Dazu einfach einen der rechten Anfasser-Punkte nach links schieben oder in der <strong>Manuellen Eingabe<\/strong> (Strg+M) bei &#8222;Breite&#8220; 0 eingeben (siehe Bild unten).<br>Damit der Balken nun von der geringen Breite zur richtigen Breite kommt, <strong>kehren wir den Pfad noch um<\/strong>. Dazu klicken wir mit der rechten Maustaste auf den Bewegungspfad im Layoutdesigner und w\u00e4hlen dann  &#8222;Pfad bearbeiten&#8220; &#8211; &#8222;Umkehren&#8220;.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/manuelle-eingabe-breite-0-1024x577.jpg\" alt=\"Manuelle Eingabe f\u00fcr Bewegungsmarke des Balkens\" class=\"wp-image-8566\" width=\"768\" height=\"433\" srcset=\"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/manuelle-eingabe-breite-0-1024x577.jpg 1024w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/manuelle-eingabe-breite-0-300x169.jpg 300w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/manuelle-eingabe-breite-0-768x433.jpg 768w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/manuelle-eingabe-breite-0.jpg 1082w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption>Breite 0 f\u00fcr den Balken<\/figcaption><\/figure><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Objekte in Dynamische Maske einf\u00fcgen<\/h4>\n\n\n\n<p>Nun kommt auch endlich die Dynamische Maske zum Zug. Diese holen wir aus der Toolbox und ziehen sie auf unser Rechteck in der Timline. In den Masken-Bereich verschieben wir den Text mit den <strong>Gro\u00dfbuchstaben<\/strong>.<\/p>\n\n\n\n<p>Jetzt kann man in der Vorschau pr\u00fcfen, ob alles funktioniert und sich \u00fcber den sch\u00f6nen Effekt freuen. <br>Wenn der Effekt gef\u00e4llt und man ihn \u00f6fter verwenden m\u00f6chte, kann man in DiaShow Ultimate und in Stages das gesamte Kapitel auch in die Toolbox ziehen und das alles dann als <a href=\"https:\/\/www.aquasoft.de\/help\/stages11\/de\/eigene_objekte_speichern.htm\">eigene Vorlage speichern.<\/a><\/p>\n\n\n\n<p class=\"has-very-light-gray-background-color has-background\">\u00dcbrigens, alle Beispiele aus diesem Blogbeitrag gibt es als Projekt zum Herunterladen im VIP-Club unter  <a href=\"https:\/\/www.aquasoft.de\/vip\/textmasken-und-maskierter-text-3-ideen\">https:\/\/www.aquasoft.de\/vip\/textmasken-und-maskierter-text-3-ideen<\/a> .<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Text ist ausgeschnitten und gibt Blick auf Bild frei<\/h2>\n\n\n\n<p>Hier gibt es eine Fl\u00e4che, unter der ein Bild liegt. Dann erscheint die Textmaske und gibt durch die ausgeschnittenen Buchstaben hindurch den Blick auf das Bild frei. W\u00e4hrend die Fl\u00e4che erscheint, findet dahinter ein Wechsel zu einem anderen Bild statt.  Es sollten nur <strong>wenige W\u00f6rter<\/strong> verwendet werden, damit die Schrift sch\u00f6n gro\u00df dargestellt werden kann.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/Text-Masken-Kreative-Ideen_0001_Ebene-2-1024x576.jpg\" alt=\"Textmaske auf einer wei\u00dfen Fl\u00e4che gibt den Blick auf das dahinterliegende Bild frei\" class=\"wp-image-8522\" width=\"768\" height=\"432\" srcset=\"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/Text-Masken-Kreative-Ideen_0001_Ebene-2-1024x576.jpg 1024w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/Text-Masken-Kreative-Ideen_0001_Ebene-2-300x169.jpg 300w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/Text-Masken-Kreative-Ideen_0001_Ebene-2-768x432.jpg 768w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption>Hinter einer Fl\u00e4che liegt ein Bild. Durch die Buchstaben  hindurch kann man es sehen.<\/figcaption><\/figure><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Aufbau in der Timeline<\/h4>\n\n\n\n<p>Hier haben wir wieder ein Kapitel, in dem verschiedene Elemente stecken:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Zwei Bilder, die einen Kameraschwenk und eine Einblendung besitzen<\/li><li>Eine Dynamische Maske mit einer Transparenzkurve<\/li><li>Ein Rechteck (<strong>vollfl\u00e4chig<\/strong>), das im Inhalts-Bereich der Dynamischen Maske steckt<\/li><li>Zwei Text-Objekte, die sich im Masken-Bereich der Dynamischen Maske befinden. Sie erscheinen mit einem Texteffekt.<\/li><\/ul>\n\n\n\n<p>Die beiden Bilder stecken in meinem Beispiel noch in einem <a href=\"https:\/\/www.aquasoft.de\/diashow\/erweiterungen\/licht-und-optik\">Bokeh-Effekt<\/a>, der ist jedoch <strong>nur dekorativ<\/strong> und f\u00fcr den Aufbau nicht wichtig.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/textmaske-mit-wei\u00dfer-fl\u00e4che-1024x450.jpg\" alt=\"Textmaske erscheint zeitversetzt und \u00fcberlagert Wechsel der Bilder\" class=\"wp-image-8562\" width=\"512\" height=\"225\" srcset=\"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/textmaske-mit-wei\u00dfer-fl\u00e4che-1024x450.jpg 1024w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/textmaske-mit-wei\u00dfer-fl\u00e4che-300x132.jpg 300w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/textmaske-mit-wei\u00dfer-fl\u00e4che-768x337.jpg 768w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/textmaske-mit-wei\u00dfer-fl\u00e4che.jpg 2003w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><figcaption>Hier sieht man gut, wie die Textmaske den Wechsel der Bilder \u00fcberlagert.<\/figcaption><\/figure><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Bilder einf\u00fcgen mit Kameraschwenk und Einblendung<\/h4>\n\n\n\n<p>Zuerst werden hintereinander zwei Fotos eingef\u00fcgt, hier ist auch eine Einblendung sinnvoll (z.B. Alphablending). Zus\u00e4tzlich habe ich den Bildern noch einen ganz leichten Kameraschwenk gegeben, der in das Bild hineinzoomt. Die Anzeigedauer der Bilder kann zwischen sieben und acht Sekunden liegen, damit <strong>sp\u00e4ter genug Zeit zum Lesen<\/strong> des Textes ist.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Text einf\u00fcgen<\/h4>\n\n\n\n<p>Die zwei Textzeilen sollen nicht gleichzeitig, sondern etwas <strong>versetzt zueinander erscheinen<\/strong>. Aus diesem Grund verwenden wir zwei Text-Objekte. Damit trotzdem alle Einstellungen gleich sind, kann man hier auch erst ein Text-Objekt so gestalten, wie man es sich vorstellt (z.B. mit Text-Effekt, Gro\u00dfbuchstaben usw.) und dieses dann <strong>kopieren<\/strong>. <\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Rechteck einsetzen und Maske einf\u00fcgen<\/h4>\n\n\n\n<p>Jetzt kann auch schon das Rechteck dazugeholt werden, es befindet sich in der Toolbox unter &#8222;Dynamische Formen&#8220;. In meinem Beispiel habe ich dem Rechteck in der Farbpalette noch ein kleines bisschen Transparenz verliehen, damit das darunter liegende Foto noch leicht hindurchschimmert.<\/p>\n\n\n\n<p>Auf dies Rechteck in der Timeline ziehen wir nun den Effekt &#8222;Dynamische Maske&#8220; aus der Toolbox. In den Masken-Bereich kommen die beiden Text-Objekte. Dabei sollte man den Screenshot oben beachten: Das Rechteck hat insgesamt eine l\u00e4ngere Dauer und die Text-Objekte werden nicht sofort angezeigt. Sie befinden sich untereinander, <strong>leicht versetzt<\/strong> (die untere Textzeile erscheint sp\u00e4ter).<\/p>\n\n\n\n<p>Wer m\u00f6chte, kann den gelben Rahmen des Masken-Effektes in der Timeline anklicken. Im Bereich &#8222;Einstellungen&#8220; kann man n\u00e4mlich unter dem Tab &#8222;Transparenz&#8220; noch eine Kurve einstellen. Diese Kurve bewirkt, dass das Rechteck nicht abrupt aufploppt, sondern etwas sanfter eingeblendet wird.<br><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/transparenzkurve-f\u00fcr-rechteck-1024x677.jpg\" alt=\"Transparenzkurve in den Einstellungen f\u00fcr die Dynamische Maske\" class=\"wp-image-8579\" width=\"512\" height=\"339\" srcset=\"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/transparenzkurve-f\u00fcr-rechteck-1024x677.jpg 1024w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/transparenzkurve-f\u00fcr-rechteck-300x198.jpg 300w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/transparenzkurve-f\u00fcr-rechteck-768x508.jpg 768w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/transparenzkurve-f\u00fcr-rechteck.jpg 1113w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><figcaption>Transparenzkurve f\u00fcr Dynamische Maske<\/figcaption><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Text erscheint unter einer Linie<\/h2>\n\n\n\n<p>Der Text schiebt sich unter einer Linie hervor, f\u00e4hrt kurz hin und her und schiebt sich dann wieder hin zur Linie, unter der er dann verschwindet. Auch die Linie verschwindet dann aus dem Bild. Hier kann man gut <strong>Ortsbezeichnungen <\/strong>oder Namen unterbringen. In diesem Beispiel kann man gut sehen, wof\u00fcr die Keyframes in <a href=\"https:\/\/www.aquasoft.de\/stages\">AquaSoft Stages<\/a> von Nutzen sind, denn hier passieren zwei Animationen gleichzeitig, die aufeinander abgestimmt sein sollten.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/Text-Masken-Kreative-Ideen_0000_Ebene-3-1024x576.jpg\" alt=\"Text, der unter einer wei\u00dfen Linie erscheint.\" class=\"wp-image-8521\" width=\"768\" height=\"432\" srcset=\"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/Text-Masken-Kreative-Ideen_0000_Ebene-3-1024x576.jpg 1024w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/Text-Masken-Kreative-Ideen_0000_Ebene-3-300x169.jpg 300w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/Text-Masken-Kreative-Ideen_0000_Ebene-3-768x432.jpg 768w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption>Text kommt unter der Linie hervor und verschwindet dann wieder darunter<\/figcaption><\/figure><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Aufbau in der Timeline<\/h4>\n\n\n\n<p>F\u00fcr den Aufbau in der Timeline ben\u00f6tigen wir<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Ein Foto (hier wurde noch der Effekt &#8222;<a href=\"https:\/\/www.aquasoft.de\/diashow\/erweiterungen\/licht-und-optik\">Glei\u00dfen<\/a>&#8220; auf das Foto gelegt, daher sind beide Elemente mit einer Flexi-Collage verbunden. Das muss aber nat\u00fcrlich nicht sein.)<\/li><li>Ein Rechteck auf den Dynamischen Formen (wird hier als Linie verwendet).<\/li><li>Die Dynamische Maske mit einem Text-Objekt und einem Rechteck als Maske f\u00fcr die obere Bildh\u00e4lfte.<\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/text-kommt-unter-linie-hervor-1024x1003.jpg\" alt=\"Maskierter Text erscheint, wenn Linie im Bild ist\" class=\"wp-image-8563\" width=\"512\" height=\"502\" srcset=\"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/text-kommt-unter-linie-hervor-1024x1003.jpg 1024w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/text-kommt-unter-linie-hervor-300x294.jpg 300w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/text-kommt-unter-linie-hervor-768x752.jpg 768w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/text-kommt-unter-linie-hervor.jpg 1035w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><figcaption>Der maskierte Text erscheint erst, wenn die wei\u00dfe Linie vollst\u00e4ndig sichtbar ist.<\/figcaption><\/figure><\/div>\n\n\n\n<p>Zuerst f\u00fcgen wir ein Kapitel-Objekt in die Timeline ein. Hier kommt in die erste Spur das Foto. Ganz wichtig ist es, das Foto an das Seitenverh\u00e4ltnis anzupassen, sodass keine schwarzen R\u00e4nder zu sehen sind. Jetzt kann es ans Animieren gehen.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Wei\u00dfe Linie animieren<\/h4>\n\n\n\n<p>Wenn wir das Rechteck aus der Toolbox in die Timeline gezogen haben, muss dessen H\u00f6he erst einmal ordentlich verringert werden, sodass eine Linie entsteht. In der Animation soll die Linie ins Bild fahren, stehen bleiben und sich dann wieder aus dem Bild schieben. Wir ben\u00f6tigen also vier <strong>Bewegungsmarken<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Marke 1<\/strong>: Linie befindet sich im nicht-sichtbaren Bildbereich<\/li><li><em>Bewegung zu Marke 2<\/em><\/li><li><strong>Marke 2<\/strong>: Linie liegt auf dem Bild<\/li><li><em>Bewegung nicht sichtbar, da keine \u00c4nderung der Postion<\/em><\/li><li><strong>Marke 3<\/strong>: Linie liegt auf dem Bild (gleiche Position wie bei Marke 2)<\/li><li><em>Bewegung zu Marke <\/em>4<\/li><li><strong>Marke 4<\/strong>: Linie befindet sich wieder im nicht-sichtbaren Bereich<\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/keyframes-animation-wei\u00dfe-linie.jpg\" alt=\"Keyframes f\u00fcr Animation der wei\u00dfen Linie\" class=\"wp-image-8601\" width=\"403\" height=\"198\" srcset=\"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/keyframes-animation-wei\u00dfe-linie.jpg 805w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/keyframes-animation-wei\u00dfe-linie-300x148.jpg 300w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/keyframes-animation-wei\u00dfe-linie-768x378.jpg 768w\" sizes=\"auto, (max-width: 403px) 100vw, 403px\" \/><figcaption>Man sieht in der Keyframe-Spur von Stages gut den Aufbau der Marken<\/figcaption><\/figure><\/div>\n\n\n\n<p>Im Screenshot aus AquaSoft Stages erkennt man ganz gut, wie viel Zeit zwischen den einzelnen Bewegungsmarken vergehen muss. Wichtig ist, dass die Linie ein Weilchen stehen bleibt, damit auch der Text genug Zeit hat, um darunter &#8222;hervorzukriechen&#8220;. &#x1f601;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Text kommt unter Linie hervor<\/h4>\n\n\n\n<p>Jetzt f\u00fcgen wir ein Text-Objekt ein. Es sieht besonders sch\u00f6n aus, wenn der Text dabei nur <strong>einzeilig<\/strong> ist.<br>Der Text soll sich erst \u00fcber der Linie befinden (er wird an dieser Stelle sp\u00e4ter durch die Maske &#8222;<strong>unsichtbar<\/strong>&#8222;). Dann soll der  Text unter die Linie kommen (ab hier wird er dann sichtbar sein), dort bleiben, um sich dann wieder \u00fcber die Linie zu bewegen und wieder unsichtbar zu werden.<br>Daf\u00fcr ben\u00f6tigen wir mindestens vier Bewegungsmarken. In meinem Beispiel sind es sogar f\u00fcnf, weil der Text nicht komplett ruhig bleibt, sondern sich unter der Linie ganz leicht verschiebt.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/animation-text-wei\u00dfe-linie-1024x354.jpg\" alt=\"Animationen aufeinander abstimmen mit Keyframes\" class=\"wp-image-8603\" width=\"768\" height=\"266\" srcset=\"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/animation-text-wei\u00dfe-linie-1024x354.jpg 1024w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/animation-text-wei\u00dfe-linie-300x104.jpg 300w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/animation-text-wei\u00dfe-linie-768x265.jpg 768w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/animation-text-wei\u00dfe-linie.jpg 2027w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption>Im Screenshot von AquaSoft Stages sieht man gut, wie die Animation der Linie und die Text-Animation aufeinander abgestimmt sind.<\/figcaption><\/figure><\/div>\n\n\n\n<p>In den Screenshots aus Stages sieht man gut, wie die Bewegungsmarken als <strong>Keyframes<\/strong> dargestellt werden. Damit kann man die Animation der Linie und die Text-Animation gut aufeinander abstimmen, das Timing f\u00e4llt leichter. Aber auch in AquaSoft DiaShow geht das, wenn man die Zeiten der Bewegungsmarken im Blick hat und gut mit der Vorschau im Layoutdesigner arbeitet.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Maske einf\u00fcgen<\/h4>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/maskierter-text-mit-wei\u00dfer-linie-in-maske.jpg\" alt=\"Maskierter Text in der Timeline\" class=\"wp-image-8667\" width=\"224\" height=\"433\" srcset=\"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/maskierter-text-mit-wei\u00dfer-linie-in-maske.jpg 448w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/maskierter-text-mit-wei\u00dfer-linie-in-maske-155x300.jpg 155w\" sizes=\"auto, (max-width: 224px) 100vw, 224px\" \/><figcaption>So soll es am Ende aussehen<\/figcaption><\/figure><\/div>\n\n\n\n<p>Nun wird es Zeit, den Text endlich unsichtbar werden zu lassen, wenn er sich <strong>\u00fcber <\/strong>der Linie befindet! Dazu brauchen wir nochmal ein Rechteck aus der Toolbox. Das wird nun einfach so verkleinert, dass es nur den <strong>Bereich <\/strong>unter der Linie bedeckt. Das Rechteck markiert jetzt den Bereich, in dem der Text sichtbar sein darf.<\/p>\n\n\n\n<p>Auf den Text ziehen wir den Masken-Effekt aus der Toolbox. In den Masken-Bereich kommt dann das eben erstellte Rechteck. Damit sollte die Animation abgeschlossen sein.<\/p>\n\n\n\n<p><em>Ich hoffe, hier sind ein paar verwertbare Anregungen dabei. Wer noch mehr Ideen f\u00fcr Beschriftungen sucht, wir haben in der Kategorie &#8222;<a href=\"https:\/\/www.aquasoft.de\/blog\/hilfe\/category\/textgestaltung\/\">Textgestaltung<\/a>&#8220; schon einiges zusammengetragen. <\/em>&#x1f60a;<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"ANLEITUNG | Textmasken und maskierter Text \ud83c\udfad\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/tu5JwpdvEmQ?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n<span id=\"post-ratings-8520\" class=\"post-ratings\"><img decoding=\"async\" src=\"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-content\/plugins\/wp-postratings\/images\/stars_crystal\/rating_on.gif\" alt=\"6 votes, average: 4,50 out of 5\" title=\"6 votes, average: 4,50 out of 5\" class=\"post-ratings-image\" \/><img decoding=\"async\" src=\"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-content\/plugins\/wp-postratings\/images\/stars_crystal\/rating_on.gif\" alt=\"6 votes, average: 4,50 out of 5\" title=\"6 votes, average: 4,50 out of 5\" class=\"post-ratings-image\" \/><img decoding=\"async\" src=\"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-content\/plugins\/wp-postratings\/images\/stars_crystal\/rating_on.gif\" alt=\"6 votes, average: 4,50 out of 5\" title=\"6 votes, average: 4,50 out of 5\" class=\"post-ratings-image\" \/><img decoding=\"async\" src=\"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-content\/plugins\/wp-postratings\/images\/stars_crystal\/rating_on.gif\" alt=\"6 votes, average: 4,50 out of 5\" title=\"6 votes, average: 4,50 out of 5\" class=\"post-ratings-image\" \/><img decoding=\"async\" src=\"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-content\/plugins\/wp-postratings\/images\/stars_crystal\/rating_half.gif\" alt=\"6 votes, average: 4,50 out of 5\" title=\"6 votes, average: 4,50 out of 5\" class=\"post-ratings-image\" \/> (<em><strong>6<\/strong> Stimme(n), Durchschnitt: <strong>4,50<\/strong><\/em>)<\/span><span id=\"post-ratings-8520-loading\" class=\"post-ratings-loading\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-content\/plugins\/wp-postratings\/images\/loading.gif\" width=\"16\" height=\"16\" class=\"post-ratings-image\" \/>Loading...<\/span>\n","protected":false},"excerpt":{"rendered":"<p>Textmasken sind ein Weg, um Text und Bild miteinander zu verbinden. Man blickt dabei durch den Text, wie durch ein Schl\u00fcsselloch.<\/p>\n","protected":false},"author":11,"featured_media":8610,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[42,94413],"tags":[95388,95399,93694,95458],"class_list":["post-8520","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-animation","category-textgestaltung","tag-dynamische-maske","tag-textanimation","tag-textmaske","tag-weisse-linie"],"uagb_featured_image_src":{"full":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/textmasken-und-maskierter-text.jpg",1440,680,false],"thumbnail":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/textmasken-und-maskierter-text-150x150.jpg",150,150,true],"medium":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/textmasken-und-maskierter-text-300x142.jpg",300,142,true],"medium_large":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/textmasken-und-maskierter-text-768x363.jpg",768,363,true],"large":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/textmasken-und-maskierter-text-1024x484.jpg",1024,484,true],"1536x1536":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/textmasken-und-maskierter-text.jpg",1440,680,false],"2048x2048":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/textmasken-und-maskierter-text.jpg",1440,680,false],"thumb-small":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/textmasken-und-maskierter-text-160x160.jpg",80,80,true],"thumb-standard":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/textmasken-und-maskierter-text-320x320.jpg",320,320,true],"thumb-medium":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/textmasken-und-maskierter-text-520x245.jpg",520,245,true],"thumb-large":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/textmasken-und-maskierter-text-720x340.jpg",720,340,true],"thumb-xlarge":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/textmasken-und-maskierter-text-980x450.jpg",980,450,true],"thumb-xxlarge":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/textmasken-und-maskierter-text-1320x500.jpg",1320,500,true],"yarpp-thumbnail":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/06\/textmasken-und-maskierter-text.jpg",120,57,false]},"uagb_author_info":{"display_name":"Nadine","author_link":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/author\/nadine-kabelitz\/"},"uagb_comment_info":7,"uagb_excerpt":"Textmasken sind ein Weg, um Text und Bild miteinander zu verbinden. Man blickt dabei durch den Text, wie durch ein Schl\u00fcsselloch.","_links":{"self":[{"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/posts\/8520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/comments?post=8520"}],"version-history":[{"count":46,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/posts\/8520\/revisions"}],"predecessor-version":[{"id":10156,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/posts\/8520\/revisions\/10156"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/media\/8610"}],"wp:attachment":[{"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/media?parent=8520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/categories?post=8520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/tags?post=8520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}